{"id":19826,"date":"2017-05-09T14:28:10","date_gmt":"2017-05-09T13:28:10","guid":{"rendered":"http:\/\/www.letourismeaparis.fr\/?p=19826"},"modified":"2017-05-09T14:28:10","modified_gmt":"2017-05-09T13:28:10","slug":"fete-du-pain-sur-le-parvis-de-notre-du-13052017-au-22052017-sur-le-parvis-de-notre-dame","status":"publish","type":"post","link":"http:\/\/www.letourismeaparis.fr\/index.php\/2017\/05\/09\/fete-du-pain-sur-le-parvis-de-notre-du-13052017-au-22052017-sur-le-parvis-de-notre-dame\/","title":{"rendered":"F\u00eate du pain sur le parvis de Notre ,du 13\/05\/2017 au 22\/05\/2017 sur le Parvis de Notre Dame"},"content":{"rendered":"<p>Chaque jour les enfants des \u00e9coles viendront regarder travailler les professionnels pr\u00e9sents et \u00e9couter leurs conseils. A leur tour, ils fa\u00e7onneront leur petit pain et repartiront la t\u00eate pleine de souvenirs et fiers de leur fabrication.<br \/>\nToute la semaine, les visiteurs pourront d\u00e9guster les pains et les autres productions des boulangers. Et la F\u00eate du pain est \u00e0 l\u2019\u00e9coute des tendances, puisqu&rsquo;une place sera r\u00e9serv\u00e9e \u00e0 un fournil bio du jeudi 17 au dimanche 21 mai.<!--more--><br \/>\nDepuis le studio \u00ab web tv \u00bb de la F\u00eate du pain, d\u00e9bats et tables rondes seront retransmis en direct sur internet, faisant intervenir des professionnels de la fili\u00e8re : boulangers, meuniers, levuriers, agriculteurs, formateurs, banquiers\u2026 L&rsquo;actualit\u00e9 du fournil sera \u00e9galement comment\u00e9e au fil des \u00e9v\u00e9nements.<br \/>\nUne cabine photo permettra aux visiteurs d&rsquo;immortaliser leur passage avec des arri\u00e8re-plans \u00ab F\u00eate du pain \u00bb et de diffuser leur photo sur les r\u00e9seaux sociaux.<br \/>\nEnfin, des t\u00eates d\u2019affiche du sport seront pr\u00e9sentes et impliqu\u00e9es en qualit\u00e9 de membres de jurys des diff\u00e9rents concours.<br \/>\n&nbsp;<br \/>\n<strong>Des \u00e9v\u00e9nements tous les jours :<\/strong><br \/>\n\u2022 Le samedi 13 mai, Anne Hidalgo, Maire de Paris, inaugurera la manifestation et pr\u00e9sidera la c\u00e9r\u00e9monie de remise du Grand Prix de la baguette de la Ville de Paris.<br \/>\nDepuis l\u2019aube, les candidats au titre de meilleure baguette des d\u00e9partements 77, 78, 91 et 95 seront \u00e0 l\u2019\u0153uvre devant le public pour pr\u00e9parer, cuire et s\u00e9lectionner leur plus belle production.<br \/>\n\u2022 Le dimanche 14 mai, ce sera au tour des candidats boulangers de Paris et de la premi\u00e8re couronne de soumettre leurs baguettes au jury.<br \/>\n\u2022 Du lundi 15 au mercredi 17 mai, place au concours national de la baguette. Toutes les r\u00e9gions seront repr\u00e9sent\u00e9es ; le vainqueur sera d\u00e9clar\u00e9 le mercredi \u00e0 17 heures.<br \/>\n\u2022 Le mardi 16 mai \u00e0 17h30, le classement des meilleurs croissants au beurre Charentes Poitou AOP sera d\u00e9voil\u00e9.<br \/>\n\u2022 Le jeudi 18 mai, une vente de produits au profit de l\u2019Op\u00e9ration \u00ab Pi\u00e8ces Jaunes \u00bb sera organis\u00e9e.<br \/>\n\u2022 Du vendredi 19 au dimanche 21, les apprentis de 6 pays europ\u00e9ens fabriqueront des sp\u00e9cialit\u00e9s boulang\u00e8res de leurs pays.<br \/>\n\u2022 Le lundi 22, la soci\u00e9t\u00e9 Lesaffre fera une d\u00e9monstration des \u00ab fourn\u00e9es du monde \u00bb.<br \/>\n<a href=\"http:\/\/fetedupain.com\/\">http:\/\/fetedupain.com\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chaque jour les enfants des \u00e9coles viendront regarder travailler les professionnels pr\u00e9sents et \u00e9couter leurs conseils. A leur tour, ils fa\u00e7onneront leur petit pain et repartiront la t\u00eate pleine de souvenirs et fiers de leur fabrication. Toute la semaine, les&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","footnotes":""},"categories":[30],"tags":[],"class_list":["post-19826","post","type-post","status-publish","format-standard","hentry","category-gastronomie"],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":18256,"url":"http:\/\/www.letourismeaparis.fr\/index.php\/2016\/05\/23\/la-fete-du-pain-a-paris-jusquau-30-mai\/","url_meta":{"origin":19826,"position":0},"title":"La f\u00eate du pain \u00e0 Paris jusqu&#039;au 30 mai","author":"Fabienne TM","date":"23 mai 2016","format":false,"excerpt":"Dans le plus grand fournil du monde (1100 m2) install\u00e9 sur le parvis de Notre-Dame au kilom\u00e8tre z\u00e9ro, les boulangers Alsaciens (invit\u00e9s d\u2019honneur) et du Grand Paris fabriqueront devant curieux et gourmets, petits et grands, pain de tradition fran\u00e7aise, subrot, pain \u00e0 la bi\u00e8re, streusel et bretzel\u2026. Le gagnant de\u2026","rel":"","context":"Dans &quot;Gastronomie&quot;","block_context":{"text":"Gastronomie","link":"http:\/\/www.letourismeaparis.fr\/index.php\/category\/gastronomie\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.letourismeaparis.fr\/wp-content\/uploads\/2016\/05\/Capture-d%C3%A2%C2%80%C2%99e%C3%8C%C2%81cran-2016-05-23-a%C3%8C%C2%80-12.42.18.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10297,"url":"http:\/\/www.letourismeaparis.fr\/index.php\/2011\/05\/15\/la-fete-du-pain-se-deroulera-a-paris-du-12-au-16-mai\/","url_meta":{"origin":19826,"position":1},"title":"La f\u00eate du pain se d\u00e9roulera \u00e0 Paris du 12 au 16 mai .","author":"Fabienne TM","date":"15 mai 2011","format":false,"excerpt":"Sur la Parvis de de la Cath\u00e9drale Notre Dame. Les boulangers normands seront \u00e0 l'honneur . Au programme : un fournil g\u00e9ant, un espace quiz interactif, une animation sur les sucres et surtout la d\u00e9couverte d'un savoir faire... Fabrication de pain ,fabrication de sp\u00e9cialit\u00e9s normandes : douillon, tarte aux pommes\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"http:\/\/www.letourismeaparis.fr\/index.php\/category\/non-classe\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":23861,"url":"http:\/\/www.letourismeaparis.fr\/index.php\/2019\/11\/29\/marche-de-noel-alsacien-gare-de-lest\/","url_meta":{"origin":19826,"position":2},"title":"March\u00e9 de No\u00ebl alsacien Gare de l\u2019Est","author":"Fabienne TM","date":"29 novembre 2019","format":false,"excerpt":"Du 4 au 20 d\u00e9cembre 2019, le March\u00e9 de No\u00ebl alsacien de la Gare de l\u2019Est installe, comme chaque ann\u00e9e depuis 1982, un petit morceau d\u2019Alsace sur le parvis de la gare ! Sur le parvis de la Gare de l\u2019Est, un chapiteau installera ses \u00e9choppes \u00e0 colombages d\u00e9cor\u00e9es de\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"http:\/\/www.letourismeaparis.fr\/index.php\/category\/non-classe\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.letourismeaparis.fr\/wp-content\/uploads\/2019\/11\/Capture-d%E2%80%99e%CC%81cran-2019-11-29-a%CC%80-12.29.03.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":21433,"url":"http:\/\/www.letourismeaparis.fr\/index.php\/2018\/10\/19\/lalsace-fetera-noel-gare-de-lest-au-marche-de-noel-alsacien-de-paris-du-5-au-8-decembre\/","url_meta":{"origin":19826,"position":3},"title":"L\u2019Alsace f\u00eatera No\u00ebl   Gare de l\u2019Est  au March\u00e9 de No\u00ebl alsacien de Paris du 5 au 8 d\u00e9cembre","author":"Fabienne TM","date":"19 octobre 2018","format":false,"excerpt":"Produits d\u2019artisans et d\u00e9gustations\u00a0 \u00a0 sur le parvis de la Gare de l\u2019Est \u00e0 Paris\u00a0\u00a0 Du 5 au 21 d\u00e9cembre, ce sera une nouvelle fois l\u2019occasion de venir d\u00e9couvrir la magie des No\u00ebls alsaciens tous les jours de 9h \u00e0 20h (10h \u00e0 19h le dimanche, 18h le vendredi21 d\u00e9cembre),\u2026","rel":"","context":"Dans &quot;Gastronomie&quot;","block_context":{"text":"Gastronomie","link":"http:\/\/www.letourismeaparis.fr\/index.php\/category\/gastronomie\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":23892,"url":"http:\/\/www.letourismeaparis.fr\/index.php\/2019\/12\/11\/marche-de-noel-alsacien-a-paris\/","url_meta":{"origin":19826,"position":4},"title":"March\u00e9 de No\u00ebl Alsacien \u00e0 Paris","author":"Fabienne TM","date":"11 d\u00e9cembre 2019","format":false,"excerpt":"Du 4 au 20 d\u00e9cembre 2019, le March\u00e9 de No\u00ebl alsacien de la Gare de l\u2019Est installe un petit morceau d\u2019Alsace sur le parvis de la gare ! Odeurs de cannelle, d\u2019anis \u00e9toil\u00e9 et de miel, ar\u00f4mes de No\u00ebl et St Nicolas g\u00e9ant en pain d\u2019\u00e9pices\u2026 Sur le parvis de\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"http:\/\/www.letourismeaparis.fr\/index.php\/category\/non-classe\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.letourismeaparis.fr\/wp-content\/uploads\/2019\/12\/Capture-d%E2%80%99e%CC%81cran-2019-12-11-a%CC%80-11.38.44.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12185,"url":"http:\/\/www.letourismeaparis.fr\/index.php\/2012\/11\/21\/marche-de-noel-alsacien-a-la-gare-de-lest\/","url_meta":{"origin":19826,"position":5},"title":"March\u00e9 de No\u00ebl Alsacien \u00e0 la Gare de l\u2019Est","author":"Fabienne TM","date":"21 novembre 2012","format":false,"excerpt":"Du 30 novembre au 15 d\u00e9cembre 2012, le March\u00e9 de No\u00ebl alsacien de la Gare de l\u2019Est investit le pav\u00e9 ! Cette ann\u00e9e, il met \u00e0 l\u2019honneur l\u2019Arbre de No\u00ebl, celui qui prend place dans nos int\u00e9rieurs et se pare de mille feux \u00e0 l\u2019approche des f\u00eates de fin d\u2019ann\u00e9es\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"http:\/\/www.letourismeaparis.fr\/index.php\/category\/non-classe\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"http:\/\/www.letourismeaparis.fr\/index.php\/wp-json\/wp\/v2\/posts\/19826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.letourismeaparis.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.letourismeaparis.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.letourismeaparis.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.letourismeaparis.fr\/index.php\/wp-json\/wp\/v2\/comments?post=19826"}],"version-history":[{"count":0,"href":"http:\/\/www.letourismeaparis.fr\/index.php\/wp-json\/wp\/v2\/posts\/19826\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.letourismeaparis.fr\/index.php\/wp-json\/wp\/v2\/media?parent=19826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.letourismeaparis.fr\/index.php\/wp-json\/wp\/v2\/categories?post=19826"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.letourismeaparis.fr\/index.php\/wp-json\/wp\/v2\/tags?post=19826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}