{"id":21064,"date":"2018-06-04T09:43:51","date_gmt":"2018-06-04T07:43:51","guid":{"rendered":"http:\/\/www.letourismeaparis.fr\/?p=21064"},"modified":"2018-06-04T09:43:51","modified_gmt":"2018-06-04T07:43:51","slug":"la-nuit-du-handicap-levenement-du-9-juin","status":"publish","type":"post","link":"http:\/\/www.letourismeaparis.fr\/index.php\/2018\/06\/04\/la-nuit-du-handicap-levenement-du-9-juin\/","title":{"rendered":"La Nuit du handicap, l&#039;\u00e9v\u00e9nement du 9 juin"},"content":{"rendered":"<h4>Le samedi 9 juin 2018, vous \u00eates invit\u00e9s par des personnes porteuses de handicap \u00e0 passer une soir\u00e9e festive et conviviale, pour faire des rencontres hors du commun !<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-21065 aligncenter\" src=\"http:\/\/www.letourismeaparis.fr\/wp-content\/uploads\/2018\/06\/Capture-d\u2019e\u0301cran-2018-06-04-a\u0300-09.30.40-300x79.png\" alt=\"\" width=\"300\" height=\"79\"><\/h4>\n<p><strong>Au programme :<\/strong><br \/>\nAp\u00e9ro, musiques, spectacles, t\u00e9moignages, films\u2026<br \/>\nLes personnes handicap\u00e9es r\u00e9v\u00e8leront leurs talents !<br \/>\n<strong>La nuit du handicap c\u2019est :<\/strong><br \/>\n&#8211; Une soir\u00e9e pour d\u00e9couvrir les personnes handicap\u00e9es dans toute leur splendeur.<br \/>\n&#8211; Une soir\u00e9e pas comme les autres, \u00e0 partager en famille ou entre amis.<br \/>\n&#8211; Parce qu\u2019on a tous des fragilit\u00e9s, et on a tous des talents et des forces aussi !<br \/>\nRendez-vous sur le Parvis de Notre-Dame-de-Paris !<!--more--><br \/>\n&nbsp;<br \/>\n17h00&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Fanfare&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Fanfare<br \/>\nMusique et danse&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Personimages<br \/>\nMime&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Foi et Lumi\u00e8re<br \/>\nFanfare&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Fanfare<br \/>\nTh\u00e9\u00e2tre \u00ab La Course des Miracles \u00bb&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Compagnie les toupies<br \/>\n&nbsp;<br \/>\n18h00&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; T\u00e9moignage, danse&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Ines de Pracomtal<br \/>\n&nbsp;<br \/>\nPr\u00e9sentation&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Au-Del\u00e0 de nos Handicaps<br \/>\nDanse \u00ab Trio du livre \u2013 Bor\u00e9ale \u00bb&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; La Possible Echapp\u00e9e<br \/>\nFanfare&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Fanfare<br \/>\nTh\u00e9\u00e2tre \u00ab L\u2019Avare \u00bb&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Ecole de th\u00e9\u00e2tre de Bonacorsi<br \/>\n&nbsp;<br \/>\n19h00&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Danse \u00ab Nuka et Molo \u00bb&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; La Possible Echapp\u00e9e<br \/>\nMusique Th\u00e9r\u00e9mine&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Compagnie les Toupies<br \/>\n&nbsp;<br \/>\n19h30&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Lancement national de la nuit du handicap<br \/>\n20h00&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Handi danse, chor\u00e9graphie&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; GEM La Boussole<br \/>\n&nbsp;<br \/>\nSlam \u00ab Quasimodo \u00bb<br \/>\net \u00ab Soir\u00e9e sur le handicap \u00bb&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; A Fond la Vie<br \/>\nClown&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Leslie Antunes<br \/>\nHandi danse danse, chor\u00e9graphie&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; GEM La Boussole<br \/>\nHip Hop et Basket&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;L\u2019Arche \u00e0 Paris<br \/>\n21h00&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Une parole pour la Nuit du handicap, Philippe Aubert, porte-parole de la Nuit du handicap et Jackson Sintina, son associ\u00e9<br \/>\n&nbsp;<br \/>\nFanfare et Oiseau sur \u00e9chasse&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Fanfare et Oiseau + Balance<br \/>\nSlam&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Sly<br \/>\nChant et Musique&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Tomb\u00e9e du Nid<br \/>\nUlysse from Mars<br \/>\n&nbsp;<br \/>\n22h00&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Musique, bal, danse&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; DJ L\u00e9o<br \/>\n&nbsp;<br \/>\nEt tout au long de la soir\u00e9e :<br \/>\nAnimations :<br \/>\n\u2013 Olympiades et Chants gestu\u00e9s&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Foi et Lumi\u00e8re<br \/>\n\u2013 Atelier Num\u00e9rique&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Cr\u00e9ative Handicap<br \/>\n\u2013 Atelier origami&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Cr\u00e9ative Handicap<br \/>\n\u2013 Jouer avec les mots&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Cr\u00e9ative Handicap<br \/>\n\u2013 Fresque, Danse&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Personimages<br \/>\n\u2013 Hip hop basket&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Arche \u00e0 Paris<br \/>\n\u2013 Grimpe Arbre&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Au-del\u00e0 de nos handicaps<br \/>\n\u2013 Quad \u00e9lectrique, Visionnage de film&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Au-del\u00e0 de nos handicaps<br \/>\n\u2013 Disco soupe, cuisine&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; A Fond la Vie<br \/>\n\u2013 parcours en fauteuil&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; APF<br \/>\n\u2013 Atelier th\u00e9\u00e2tre, V\u00e9los&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Compagnie Les Toupies<br \/>\n\u2013 Sculpture moulage verre, sirop de glace, Chocolat&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; La Bonne Impression<br \/>\n\u2013 Quizz avec ordinateur&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Scouts Vent du Large<br \/>\n\u2013 Portraits et caricature&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; AFTC<br \/>\n\u2013 Tennis de table&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Handisport 92<br \/>\n\u2013 Meubles G\u00e9ants&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Association des Personnes de Petite Taille<br \/>\n\u2013 Yoga du rire&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Glip Polio<br \/>\n\u2013 Coiffeur&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Luc Pain<br \/>\n&nbsp;<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le samedi 9 juin 2018, vous \u00eates invit\u00e9s par des personnes porteuses de handicap \u00e0 passer une soir\u00e9e festive et conviviale, pour faire des rencontres hors du commun ! Au programme : Ap\u00e9ro, musiques, spectacles, t\u00e9moignages, films\u2026 Les personnes handicap\u00e9es&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","footnotes":""},"categories":[12],"tags":[],"class_list":["post-21064","post","type-post","status-publish","format-standard","hentry","category-bonnes-oeuvres"],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":10275,"url":"http:\/\/www.letourismeaparis.fr\/index.php\/2011\/05\/08\/courir-ensemble-le-15-mai-2011-au-bois-de-boulogne\/","url_meta":{"origin":21064,"position":0},"title":"&quot;Courir  ensemble&quot;  le 15 mai 2011 au Bois de Boulogne.","author":"Fabienne TM","date":"8 mai 2011","format":false,"excerpt":"Le but est d'organiser un espace de rencontres sportif, ludique et convivial entre personnes valides et handicap\u00e9es.Pr\u00e8s de 160 b\u00e9n\u00e9voles\u00a0 seront mobilis\u00e9s pour accueillir pr\u00e8s de 2000 personnes valides et handicap\u00e9es Courir Ensemble permet ainsi un \u00e9change au-del\u00e0 des diff\u00e9rences et contribue \u00e9galement, gr\u00e2ce \u00e0 vos inscriptions, au financement des\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"http:\/\/www.letourismeaparis.fr\/index.php\/category\/non-classe\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":18407,"url":"http:\/\/www.letourismeaparis.fr\/index.php\/2016\/06\/22\/grand-week-end-festif-quai-branlypour-ses-10-ans\/","url_meta":{"origin":21064,"position":1},"title":"Grand week- end festif quai Branly pour ses 10 ans","author":"Fabienne TM","date":"22 juin 2016","format":false,"excerpt":"\u00a0 \u00a0A l''occasion des 10 ans du mus\u00e9e, une programmation exceptionnelle est propos\u00e9e en continu du samedi25 juin le matin au dimanche26 juin le soir, soit plus de 30 heures d'ouverture non-stop. Deux jours de best-of des activit\u00e9s propos\u00e9es aux visiteurs pendant ces 10 derni\u00e8res ann\u00e9es dans le jardin, sur\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"http:\/\/www.letourismeaparis.fr\/index.php\/category\/non-classe\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":15361,"url":"http:\/\/www.letourismeaparis.fr\/index.php\/2014\/06\/25\/tournoi-de-rugby-7-de-coeur-versailles-les-28-et-29-juin-au-stade-de-porchefontaine-versailles\/","url_meta":{"origin":21064,"position":2},"title":"Tournoi  de rugby ,7 de C\u0153ur \u00e0 Versailles Les 28 et 29 juin  au Stade de Porchefontaine \u00e0 Versailles.","author":"Fabienne TM","date":"25 juin 2014","format":false,"excerpt":"\u00a0 \u00a0Ce tournoi de rugby \u00e0 7, devenu international, est cette ann\u00e9e soutenu par 2 ambassadeurs de renom : le joueur du Racing M\u00e9tro 92, Henri Chavancy et la journaliste Isabelle Ithurburu. Les \u00e9quipes qui participent au tournoi doivent toutes collecter la somme minimum de 800 euros au profit de\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"http:\/\/www.letourismeaparis.fr\/index.php\/category\/non-classe\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":18315,"url":"http:\/\/www.letourismeaparis.fr\/index.php\/2016\/06\/10\/un-grand-week-end-anniversaire-au-musee-du-quai-branly-samedi-2506-et-dimanche-260616\/","url_meta":{"origin":21064,"position":3},"title":"Un grand week-end anniversaire  au mus\u00e9e du quai Branly  ,  Samedi 25\/06 et dimanche 26\/06\/16","author":"Fabienne TM","date":"10 juin 2016","format":false,"excerpt":"\u00c0 l'occasion des 10 ans du mus\u00e9e, une programmation exceptionnelle est propos\u00e9e en continu du samedi matin au dimanche soir, soit plus de 30 heures d'ouverture non-stop. Deux jours de best-of des activit\u00e9s propos\u00e9es aux visiteurs pendant ces 10 derni\u00e8res ann\u00e9es dans le jardin, sur le plateau des collections, dans\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"http:\/\/www.letourismeaparis.fr\/index.php\/category\/non-classe\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":7870,"url":"http:\/\/www.letourismeaparis.fr\/index.php\/2010\/06\/15\/des-idees-pour-les-week-end-de-superbes-animations-a-vaux-le-vicomte-les-20-et-26-juin\/","url_meta":{"origin":21064,"position":4},"title":"De superbes animations \u00e0 Vaux le Vicomte les dimanche  20 juin et samedi 26 juin","author":"Fabienne TM","date":"15 juin 2010","format":false,"excerpt":"Soir\u00e9es aux chandelles et feux d\u2019artifice jusqu'au 9 octobre, tous les 1ers et 3\u00e8mes samedis de chaque mois Dimanche 20 juin 2010 : Journ\u00e9e Grand Si\u00e8cle et d\u00e9jeuner sur l\u2019herbe costum\u00e9 vaux le vicomte les visiteurs peuvent venir avec leur propre costume du 17\u00e8me ou 18\u00e8me si\u00e8cle et d\u00e9jeuner sur\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"http:\/\/www.letourismeaparis.fr\/index.php\/category\/non-classe\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3088,"url":"http:\/\/www.letourismeaparis.fr\/index.php\/2009\/06\/09\/soiree-samedi-13-juin-en-faveur-de-la-francophonie-au-liban\/","url_meta":{"origin":21064,"position":5},"title":"Soir\u00e9e samedi 13 juin en faveur de la francophonie au Liban","author":"Fabienne TM","date":"9 juin 2009","format":false,"excerpt":"L'association SESAME ET TALENTS vous propose SOIREE \"BEFORE SUMMER\": une soir\u00e9e\u00a0 pour soutenir les projets de l'association E.M.A. en faveur de la francophonie au Liban. Le Samedi 13 Juin 2009 \u00e0 partir de 22h00 http:\/\/www.ema.asso.fr http:\/\/sesameettalents.free.fr Espace Saint Pierre 121' avenue Achille Peretti\u00a0 92200 Neuilly s\/ Seine","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"http:\/\/www.letourismeaparis.fr\/index.php\/category\/non-classe\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"http:\/\/www.letourismeaparis.fr\/index.php\/wp-json\/wp\/v2\/posts\/21064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.letourismeaparis.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.letourismeaparis.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.letourismeaparis.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.letourismeaparis.fr\/index.php\/wp-json\/wp\/v2\/comments?post=21064"}],"version-history":[{"count":0,"href":"http:\/\/www.letourismeaparis.fr\/index.php\/wp-json\/wp\/v2\/posts\/21064\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.letourismeaparis.fr\/index.php\/wp-json\/wp\/v2\/media?parent=21064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.letourismeaparis.fr\/index.php\/wp-json\/wp\/v2\/categories?post=21064"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.letourismeaparis.fr\/index.php\/wp-json\/wp\/v2\/tags?post=21064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}